{"id":1251,"date":"2023-08-16T14:22:15","date_gmt":"2023-08-16T14:22:15","guid":{"rendered":"https:\/\/my.qnproducts.digital\/wellness\/"},"modified":"2024-01-22T05:45:10","modified_gmt":"2024-01-22T05:45:10","slug":"wellness","status":"publish","type":"page","link":"https:\/\/my.qnproducts.digital\/ar\/wellness\/","title":{"rendered":"\u0627\u0644\u0639\u0627\u0641\u064a\u0629"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Product Grid&#8221; module_class=&#8221;qi-brand-section&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; display_conditions=&#8221;W10=&#8221; custom_padding=&#8221;10px||23%||false|false&#8221; custom_padding_tablet=&#8221;0px||3%||false|false&#8221; custom_padding_phone=&#8221;||3%||false|false&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|||on|||||&#8221; header_2_font_size=&#8221;24px&#8221; background_layout=&#8221;dark&#8221; display_conditions=&#8221;W10=&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>\u0627\u062e\u062a\u0631\u0652 \u0627\u0644\u0645\u0646\u062a\u062c<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; make_equal=&#8221;on&#8221; module_class=&#8221;qi-image-boxes-row&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb url=&#8221;https:\/\/my.qnproducts.digital\/ar\/wellness\/chi-pendant-4\/&#8221; image=&#8221;https:\/\/my.qnproducts.digital\/wp-content\/uploads\/2023\/08\/CP4-600-x-600_0.jpg&#8221; module_class=&#8221;qi-image-boxes-item&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;16px|16px|16px|16px|true|true&#8221; animation=&#8221;off&#8221; link_option_url=&#8221;https:\/\/my.qnproducts.digital\/ar\/wellness\/chi-pendant-4\/&#8221; custom_css_main_element=&#8221;background: -webkit-gradient(linear, left top, left bottom, from(white), to(white)) padding-box,||            -webkit-gradient(linear, left top, left bottom, from(rgba(255, 111, 0, 1)), to(rgba(196, 41, 113, 1))) border-box;background: linear-gradient(white, white) padding-box,||            linear-gradient(to bottom, rgba(255, 111, 0, 1), rgba(196, 41, 113, 1)) border-box;||border: 4px solid transparent;||border-radius: 16px;||-webkit-box-shadow: 0px 6px 6px -3px rgba(0, 0, 0, 0.20), 0px 10px 14px 1px rgba(0, 0, 0, 0.14), 0px 4px 18px 3px rgba(0, 0, 0, 0.12);||box-shadow: 0px 6px 6px -3px rgba(0, 0, 0, 0.20), 0px 10px 14px 1px rgba(0, 0, 0, 0.14), 0px 4px 18px 3px rgba(0, 0, 0, 0.12);&#8221; custom_css_blurb_image=&#8221;margin-bottom: 16px;&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"qi-image-boxes-btn\"><a href=\"https:\/\/my.qnproducts.digital\/ar\/wellness\/chi-pendant-4\/\">Chi Pendant 4<\/a><\/div>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb url=&#8221;https:\/\/my.qnproducts.digital\/ar\/wellness\/bio-disc-3\/&#8221; image=&#8221;https:\/\/my.qnproducts.digital\/wp-content\/uploads\/2023\/08\/BioDisc3-600-x-600_0.jpg&#8221; module_class=&#8221;qi-image-boxes-item&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;16px|16px|16px|16px|true|true&#8221; animation=&#8221;off&#8221; link_option_url=&#8221;https:\/\/my.qnproducts.digital\/ar\/wellness\/bio-disc-3\/&#8221; custom_css_main_element=&#8221;background: -webkit-gradient(linear, left top, left bottom, from(white), to(white)) padding-box,||            -webkit-gradient(linear, left top, left bottom, from(rgba(255, 111, 0, 1)), to(rgba(196, 41, 113, 1))) border-box;background: linear-gradient(white, white) padding-box,||            linear-gradient(to bottom, rgba(255, 111, 0, 1), rgba(196, 41, 113, 1)) border-box;||border: 4px solid transparent;||border-radius: 16px;||-webkit-box-shadow: 0px 6px 6px -3px rgba(0, 0, 0, 0.20), 0px 10px 14px 1px rgba(0, 0, 0, 0.14), 0px 4px 18px 3px rgba(0, 0, 0, 0.12);||box-shadow: 0px 6px 6px -3px rgba(0, 0, 0, 0.20), 0px 10px 14px 1px rgba(0, 0, 0, 0.14), 0px 4px 18px 3px rgba(0, 0, 0, 0.12);&#8221; custom_css_blurb_image=&#8221;margin-bottom: 16px;&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"qi-image-boxes-btn\"><a href=\"https:\/\/my.qnproducts.digital\/ar\/wellness\/bio-disc-3\/\">Bio Disc 3<\/a><\/div>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb url=&#8221;https:\/\/my.qnproducts.digital\/ar\/wellness\/bio-light-3\/&#8221; image=&#8221;https:\/\/my.qnproducts.digital\/wp-content\/uploads\/2023\/08\/Bio_Light_3-600-x-600_0.jpg&#8221; module_class=&#8221;qi-image-boxes-item&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;16px|16px|16px|16px|true|true&#8221; animation=&#8221;off&#8221; link_option_url=&#8221;https:\/\/my.qnproducts.digital\/ar\/wellness\/bio-light-3\/&#8221; custom_css_main_element=&#8221;background: -webkit-gradient(linear, left top, left bottom, from(white), to(white)) padding-box,||            -webkit-gradient(linear, left top, left bottom, from(rgba(255, 111, 0, 1)), to(rgba(196, 41, 113, 1))) border-box;background: linear-gradient(white, white) padding-box,||            linear-gradient(to bottom, rgba(255, 111, 0, 1), rgba(196, 41, 113, 1)) border-box;||border: 4px solid transparent;||border-radius: 16px;||-webkit-box-shadow: 0px 6px 6px -3px rgba(0, 0, 0, 0.20), 0px 10px 14px 1px rgba(0, 0, 0, 0.14), 0px 4px 18px 3px rgba(0, 0, 0, 0.12);||box-shadow: 0px 6px 6px -3px rgba(0, 0, 0, 0.20), 0px 10px 14px 1px rgba(0, 0, 0, 0.14), 0px 4px 18px 3px rgba(0, 0, 0, 0.12);&#8221; custom_css_blurb_image=&#8221;margin-bottom: 16px;&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"qi-image-boxes-btn\"><a href=\"https:\/\/my.qnproducts.digital\/ar\/wellness\/bio-light-3\/\">Bio Light 3<\/a><\/div>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u062e\u062a\u0631\u0652 \u0627\u0644\u0645\u0646\u062a\u062cChi Pendant 4Bio Disc 3Bio Light 3<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1251","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/my.qnproducts.digital\/ar\/wp-json\/wp\/v2\/pages\/1251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my.qnproducts.digital\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/my.qnproducts.digital\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/my.qnproducts.digital\/ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/my.qnproducts.digital\/ar\/wp-json\/wp\/v2\/comments?post=1251"}],"version-history":[{"count":0,"href":"https:\/\/my.qnproducts.digital\/ar\/wp-json\/wp\/v2\/pages\/1251\/revisions"}],"wp:attachment":[{"href":"https:\/\/my.qnproducts.digital\/ar\/wp-json\/wp\/v2\/media?parent=1251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}